{"id":3892,"date":"2026-07-15T14:13:31","date_gmt":"2026-07-15T12:13:31","guid":{"rendered":"https:\/\/lecture.jose-marcio.org\/blog\/?p=3892"},"modified":"2026-07-15T14:32:35","modified_gmt":"2026-07-15T12:32:35","slug":"leo-coutellec-la-science-au-pluriel","status":"publish","type":"post","link":"https:\/\/lecture.jose-marcio.org\/blog\/2026\/07\/15\/leo-coutellec-la-science-au-pluriel\/","title":{"rendered":"L\u00e9o Coutellec &#8211; La Science au pluriel"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3894 alignright\" src=\"https:\/\/lecture.jose-marcio.org\/blog\/wp-content\/uploads\/2026\/07\/LeoCoutellec-LaScienceAuPluriel-190x300.jpg\" alt=\"\" width=\"190\" height=\"300\" srcset=\"https:\/\/lecture.jose-marcio.org\/blog\/wp-content\/uploads\/2026\/07\/LeoCoutellec-LaScienceAuPluriel-190x300.jpg 190w, https:\/\/lecture.jose-marcio.org\/blog\/wp-content\/uploads\/2026\/07\/LeoCoutellec-LaScienceAuPluriel-649x1024.jpg 649w, https:\/\/lecture.jose-marcio.org\/blog\/wp-content\/uploads\/2026\/07\/LeoCoutellec-LaScienceAuPluriel-768x1211.jpg 768w, https:\/\/lecture.jose-marcio.org\/blog\/wp-content\/uploads\/2026\/07\/LeoCoutellec-LaScienceAuPluriel.jpg 951w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/>Ce livre traite d&rsquo;une possible \u00e9volution de la science en ce qui concerne l&rsquo;\u00e9pist\u00e9mologie et l&rsquo;\u00e9thique en science. Pour r\u00e9sumer, accepter et admettre que la science puisse ne pas \u00eatre neutre.<\/p>\n<p>Je ne partage pas cette opinion parce qu&rsquo;elle risque de faire perdre l&rsquo;objectivit\u00e9 de la recherche scientifique. Bien s\u00fbr, aucun scientifique n&rsquo;est neutre, mais il y a des pas \u00e0 ne pas franchir. Cette envie de non-neutralit\u00e9 vient surtout des sciences humaines et le d\u00e9bat est historique.<\/p>\n<p>Pour comprendre, commen\u00e7ons par les sciences exactes, avec une citation de Roger Penrose dans \u00ab\u00a0Artificial Intelligence versus Natural Intelligence [RP]<\/p>\n<blockquote><p>\u00ab Ma fa\u00e7on d&rsquo;envisager la science consiste \u00e0 chercher \u00e0 d\u00e9couvrir ce qui est vrai au sujet du monde. Il n&rsquo;y a donc pas d&rsquo;enjeu moral en soi ; la question morale est distincte. \u00bb La science cherche \u00e0 comprendre comment le monde fonctionne. Vient ensuite la technologie, qui s&rsquo;int\u00e9resse \u00e0 la mani\u00e8re d&rsquo;exploiter les connaissances scientifiques. Bien qu&rsquo;elle entretienne un lien \u00e9troit avec la science, la technologie ne se confond pas avec elle. La technologie exerce une influence consid\u00e9rable et constante sur le quotidien des gens, ce qui soul\u00e8ve in\u00e9vitablement des questions d&rsquo;ordre moral. Ainsi, selon Penrose, l&rsquo;usage de la technologie \u2014 et plus particuli\u00e8rement l&rsquo;utilisation, bonne ou mauvaise, de la science \u2014 est intimement li\u00e9 \u00e0 la morale. Penrose est tr\u00e8s clair \u00e0 ce sujet : \u00ab Lorsque je fais de la science, je cherche \u00e0 comprendre le fonctionnement du monde, et non \u00e0 acqu\u00e9rir du pouvoir. \u00bb La science ne vise pas \u00e0 contr\u00f4ler le monde ; c&rsquo;est l\u00e0 l&rsquo;objectif de la technologie. La technologie et la morale sont des domaines distincts de la science, bien qu&rsquo;ils en d\u00e9pendent : lorsque la science \u00e9volue, ces deux autres domaines doivent en tenir compte et prendre en consid\u00e9ration ses enseignements.<\/p><\/blockquote>\n<p>Ce texte, tr\u00e8s synth\u00e9tique, r\u00e9sume bien l&rsquo;id\u00e9e.<\/p>\n<p>Interpr\u00e9tons cela. Penrose s\u00e9pare, \u00e0 juste titre, \u00ab\u00a0Science\u00a0\u00bb et \u00ab\u00a0Technologie\u00a0\u00bb, que l&rsquo;on peut appeler autrement, comme \u00ab\u00a0Science Appliqu\u00e9e\u00a0\u00bb. Cette s\u00e9paration est importante puisque si la Science est libre de tout \u00e9tudier elle n&rsquo;a pas vocation \u00e0 prendre le pouvoir ou influencer des prises de d\u00e9cisions : elle doit \u00eatre neutre. La Science est factuelle et immuable, tant qu&rsquo;il n&rsquo;y a pas des nouvelles d\u00e9couvertes. Cela se r\u00e9sume par le mot Objectivit\u00e9 et les chercheurs doivent laisser leurs opinions personnelles \u00e0 la maison. \u00c7a revient \u00e0 la partie Science Appliqu\u00e9e de trouver des applications de la partie Science, tenant compte de la morale et de l&rsquo;\u00e9thique, visant le bien de la soci\u00e9t\u00e9.<\/p>\n<p>Le cas des Sciences Humaines est particulier et c&rsquo;est o\u00f9 le manque de neutralit\u00e9 est plus courant et plus n\u00e9faste \u00e0 cause de cette non-neutralit\u00e9. La fronti\u00e8re entre ce qui serait de la Science et ce qui serait de la Science appliqu\u00e9e n&rsquo;est pas aussi nette comme dans les Sciences exactes.<\/p>\n<p>Il existe un courant qui sugg\u00e8re que, dans les \u00e9tudes dans ces disciplines, les chercheurs ne doivent pas faire parti de l&rsquo;objet d&rsquo;\u00e9tude [SG], pour la simple raison que souvent, il ne peut prendre suffisamment de distance du sujet d&rsquo;\u00e9tude. Par exemple, quelqu&rsquo;un qui est touch\u00e9 par une certaine discrimination peut t\u00e9moigner, mais ne doit mener, lui-m\u00eame, des travaux de recherche sur cette discrimination particuli\u00e8re. De m\u00eame pour des faits historiques.<\/p>\n<p>Il faut dire un mot ici au sujet du militantisme en recherche, un ph\u00e9nom\u00e8ne en mode. Une des qualit\u00e9s primordiales d&rsquo;un chercheur est l&rsquo;ouverture d&rsquo;esprit, l&rsquo;aptitude de, toujours, se poser des questions et de pouvoir changer d&rsquo;avis face aux faits nouveaux ou des arguments et dialogues. Une grande capacit\u00e9 d&rsquo;\u00e9coute. Le probl\u00e8me avec les militants est qu&rsquo;ils sont dans la d\u00e9fense de th\u00e8ses sp\u00e9cifiques, toujours \u00ab\u00a0droits dans leurs bottes\u00a0\u00bb, pratiquant le pros\u00e9lytisme et incapables de changer d&rsquo;avis. Aucune ouverture d&rsquo;esprit, impossible d&rsquo;admettre la possibilit\u00e9 d&rsquo;une d\u00e9marche diff\u00e9rente de la sienne. C&rsquo;est, le plus souvent, li\u00e9.\u00e0 des id\u00e9ologies ou des th\u00e8mes tels l&rsquo;\u00e9cologie ou la politique. Tel comportement est, par d\u00e9finition, incompatible avec celui d&rsquo;un chercheur digne de ce nom.<\/p>\n<p>Quelle cr\u00e9dibilit\u00e9 peut-on accorder \u00e0 certains chercheurs que profitent de leur renomm\u00e9e dans un domaine pour militer dans un autre ? Je cite, par exemple, Patrick Boucheron, historien qui a voulu interdire l&rsquo;apparition d&rsquo;un ouvrage critiquant le wokisme ? Johann Chapoutot, historien qui d\u00e9fend des th\u00e8mes proches de l&rsquo;extr\u00eame gauche (LFI), ou encore Aur\u00e9lien Barrau, probablement un bon physicien, mais grand militant de l&rsquo;\u00e9cologie. Et, pour finir, S\u00e9bastien Bohler, journaliste avec un doctorat en neurosciences, mais, lui aussi, militant \u00e9cologique. Il me semble l\u00e9gitime de se poser des questions sur leur cr\u00e9dibilit\u00e9. Un physicien disait r\u00e9cemment : <em>\u00ab\u00a0Il n&rsquo;y a pas de corr\u00e9lation entre militantisme et comp\u00e9tence\u00a0\u00bb<\/em>.<\/p>\n<p>\u00c0 une \u00e9poque o\u00f9 le militantisme est \u00e0 la mode, on peut comprendre le souhait qui peut avoir certains scientifiques pour qu&rsquo;ils puissent utiliser leur activit\u00e9 de recherche pour faire passer leurs opinions personnelles. Mais cela cr\u00e9e le risque de polluer la Science par des id\u00e9ologies qui n&rsquo;ont, objectivement, rien \u00e0 faire l\u00e0-dedans. Au contraire de la th\u00e8se de l&rsquo;auteur, le but de la Science n&rsquo;est pas la recherche de pouvoir. La Science n&rsquo;a aucune responsabilit\u00e9 sur ses r\u00e9sultats. C&rsquo;est l&rsquo;utilisation qui en est faite par la soci\u00e9t\u00e9 et par les chercheurs qui se sentent impliqu\u00e9s que peut \u00eatre responsabilis\u00e9e.<\/p>\n<p>Malgr\u00e9 mon d\u00e9saccord de principes avec la th\u00e8se d\u00e9velopp\u00e9e dans l&rsquo;ouvrage, \u00e7a reste un contenu int\u00e9ressant, si on souhaite conna\u00eetre les arguments de ces th\u00e8ses.<\/p>\n<p>[RP] Roger Penrose et all &#8211; Artificial Intelligence versus Natural Intelligence\u00a0\u00bb &#8211; Springer Nature &#8211; 2022<\/p>\n<p>[SG] Serge Genest &#8211; Recherche anthropologique : techniques et m\u00e9thodes &#8211; Perspectives anthropologiques. Un collectif d&rsquo;anthropologues qu\u00e9b\u00e9cois, chapitre 19, pp. 333 \u00e0 344. Montr\u00e9al: Les \u00c9ditions du Renouveau p\u00e9dagogique, 1979.<\/p>\n<h2>Citations<\/h2>\n<h2>Quatri\u00e8me de Couverture<\/h2>\n<p>Plusieurs hypoth\u00e8ses en \u00e9pist\u00e9mologie sont formul\u00e9es dans cet ouvrage pour penser et agir sur le pluralisme des sciences. L\u00e9o Coutellec propose de construire un espace de r\u00e9flexion critique sur ce qu&rsquo;il nomme la science impliqu\u00e9e. Nom d&rsquo;une science qui prend acte de sa responsabilit\u00e9, attentive aux cons\u00e9quences, une science qui ouvre la possibilit\u00e9 d&rsquo;un questionnement sur ses finalit\u00e9s, qui ne revendique plus sa neutralit\u00e9 axiologique pour affirmer son objectivit\u00e9, la science impliqu\u00e9e vise au partage des savoirs et des pouvoirs li\u00e9s \u00e0 ces savoirs. Pour l&rsquo;auteur, l&rsquo;enjeu est de doter la science d&rsquo;un nouveau principe d\u00e9mocratique qui permettrait, non pas de la sortir de la tourmente soci\u00e9tale dans laquelle elle semble \u00eatre prise, mais de la penser au pluriel dans la profondeur de son implication radicale au r\u00e9el. Sa r\u00e9flexion \u00e9pist\u00e9mologique sur les sciences rejoint celle de l&rsquo;\u00e9thique.<\/p>\n<p>Issu d&rsquo;une conf\u00e9rence donn\u00e9e \u00e0 l&rsquo;occasion du 20e anniversaire du groupe Sciences en questions, ce petit ouvrage renouvelle les r\u00e9flexions \u00e9pist\u00e9mologiques et philosophiques au sein de la d\u00e9marche scientifique et notre fa\u00e7on de penser la responsabilit\u00e9 dans les sciences.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce livre traite d&rsquo;une possible \u00e9volution de la science en ce qui concerne l&rsquo;\u00e9pist\u00e9mologie et l&rsquo;\u00e9thique en science. Pour r\u00e9sumer, accepter et admettre que la science puisse ne pas \u00eatre neutre. Je ne partage pas cette opinion parce qu&rsquo;elle risque<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,21,19,6],"tags":[],"class_list":["post-3892","post","type-post","status-publish","format-standard","hentry","category-lecture","category-philosophie","category-sciences","category-sociologie","comments-off"],"_links":{"self":[{"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/posts\/3892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/comments?post=3892"}],"version-history":[{"count":3,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/posts\/3892\/revisions"}],"predecessor-version":[{"id":3896,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/posts\/3892\/revisions\/3896"}],"wp:attachment":[{"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/media?parent=3892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/categories?post=3892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lecture.jose-marcio.org\/blog\/wp-json\/wp\/v2\/tags?post=3892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}